{"id":1888,"date":"2024-12-26T05:47:51","date_gmt":"2024-12-26T05:47:51","guid":{"rendered":"https:\/\/kelingmed.com\/?p=1888"},"modified":"2024-12-26T05:51:14","modified_gmt":"2024-12-26T05:51:14","slug":"2024-arab-health-keling-medical","status":"publish","type":"post","link":"https:\/\/kelingmed.com\/de\/2024-arab-health-keling-medical\/","title":{"rendered":"2024 Arab Health Keling Medical"},"content":{"rendered":"<h2>Keling Medical auf der Arab Health 2024: Innovationen im Gesundheitswesen durch strategische Partnerschaften vorantreiben<\/h2>\n<p>Keling Medical \u2013 China\u2019s leading medical devices manufacturer \u2013 attended Arab Health 2024, one of the largest and most powerful medical trade shows in the Middle East and internationally.&nbsp;This event was a perfect opportunity to present our advanced solutions and meet with leaders, distributors, and medical professionals.<\/p>\n<h3>Gesundheitspflege wie wir sie heute und in Zukunft sehen?<\/h3>\n<p>We at Keling Medical are motivated to raise the standard of global healthcare through innovation, quality and collaboration.&nbsp;We demonstrated an entire set of medical devices to support today\u2019s healthcare systems at Arab Health 2024.&nbsp;Key product categories included:<\/p>\n<p>Vollst\u00e4ndiges chirurgisches System: High-Depth-Operationstische, hochmoderne chirurgische Beleuchtung und Vollspektrum-Systeme zur Maximierung von Arbeitsabl\u00e4ufen und Patientenzufriedenheit.<\/p>\n<p>Krankenhausm\u00f6bel und Mobilit\u00e4tshilfen: Bequeme Krankenhausbetten, Patiententransferger\u00e4te und medizinische Wagen, die die Patientenversorgung und Effizienz unterst\u00fctzen.<\/p>\n<p>Diagnostische und bildgebende Ger\u00e4te: Hochmoderne Diagnoseger\u00e4te, die pr\u00e4zise, vorhersagbare Ergebnisse liefern, um wirksame und rechtzeitige medizinische Entscheidungen zu treffen.<\/p>\n<p>Ger\u00e4te f\u00fcr die Vitalpflege: Bew\u00e4hrte und neue L\u00f6sungen wie Beatmungsger\u00e4te, An\u00e4sthesieger\u00e4te und Multiparameter-Monitore, die f\u00fcr den Einsatz in den speziellsten klinischen Situationen konzipiert sind.<\/p>\n<h3>Warum Verteiler Keling Medical w\u00e4hlen<\/h3>\n<p>Keling Medical is a trusted medical device partner for more than 20 years.&nbsp;Our unique strengths include:<\/p>\n<p>Zertifizierte Qualit\u00e4t: Unsere Produkte sind nach den internationalen Top-Qualit\u00e4tsstandards CE und ISO zertifiziert, um die Qualit\u00e4t und die Einhaltung der weltweiten Gesundheitsvorschriften zu gew\u00e4hrleisten.<\/p>\n<p>Auf Innovation fokussiert: Wir verf\u00fcgen \u00fcber ein Forschungs- und Entwicklungsteam, das mit den Gesundheitsdienstleistern zusammenarbeitet, um die Technologien zu erneuern und weiterzuentwickeln.<\/p>\n<p>L\u00f6sungen, die sich dem Markt anpassen: Unsere Produkte werden von unseren Vertriebsh\u00e4ndlern an die verschiedenen M\u00e4rkte angepasst, was f\u00fcr Flexibilit\u00e4t und Marktanpassung sorgt.<\/p>\n<p>Unterst\u00fctzend und detailliert: Von der ersten Anfrage bis zum After-Sales-Support bieten wir Ihnen die Unterst\u00fctzung, die Sie f\u00fcr den Aufbau langfristiger Partnerschaften ben\u00f6tigen.<\/p>\n<h3>Arabische Gesundheit 2024: Ein Raum f\u00fcr Zusammenarbeit.<\/h3>\n<p>We participated in Arab Health 2024 because we want to build meaningful partnerships with distributors and dealers all around the world.&nbsp;The conference gave us a chance to share how our products and services can be used to solve regional healthcare issues and drive collaboration.<\/p>\n<h3>Partner bei Keling Medical<\/h3>\n<p>With Keling Medical aiming to grow globally, we\u2019re looking for distributors and dealers with similar mission of providing quality medical solutions to the medical community.&nbsp;Working with us gives you:<\/p>\n<h3>Ein umfangreiches und flexibles Produktangebot.<\/h3>\n<p>Angebote zu einem wettbewerbsf\u00e4higen Preis, der zu Ihrer Branche passt.<\/p>\n<p>Hilfe bei der technischen Ausbildung und beim Marketing, um Ihnen zum Erfolg zu verhelfen.<\/p>\n<h3>Lassen Sie uns gemeinsam das Gesundheitswesen der Zukunft gestalten.<\/h3>\n<p>Join us at the Keling Medical network and work with us to improve health across the globe.&nbsp;Give us a call today to discuss partnership possibilities and how we can help grow your business.<\/p>\n<p data-pm-slice=\"1 1 []\">\ud83d\udce7 E-Mail: <a href=\"mailto:inquiry@shkeling.com\">inquiry@shkeling.com<\/a><br \/>\ud83c\udf10 Website: <a href=\"http:\/\/kelingmed.com\">kelingmed.com<\/a><\/p>\n<p>Wir freuen uns darauf, mit Ihnen eine erfolgreiche Partnerschaft aufzubauen!<\/p>\n<form id=\"wpforms-form-1843\" data-formid=\"1843\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/wp-admin\/admin-ajax.php\" data-token=\"e244793b799d3e032bfa81f0ac38ae44\" data-trp-original-action=\"\/wp-admin\/admin-ajax.php\"><noscript>Please enable JavaScript in your browser to complete this form.<\/noscript>Please enable JavaScript in your browser to complete this form.<label for=\"wpforms-1843-field_1\" aria-hidden=\"false\">Layout<\/label><label for=\"wpforms-1843-field_2\">Name *<\/label><input type=\"text\" id=\"wpforms-1843-field_2\" name=\"wpforms[fields][2]\" aria-errormessage=\"wpforms-1843-field_2-error\" required><label for=\"wpforms-1843-field_5\">Phone\/WhatsApp *<\/label><input type=\"tel\" id=\"wpforms-1843-field_5\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][5]\" aria-errormessage=\"wpforms-1843-field_5-error\" required><label for=\"wpforms-1843-field_3\">Email *<\/label><input type=\"email\" id=\"wpforms-1843-field_3\" name=\"wpforms[fields][3]\" spellcheck=\"false\" aria-errormessage=\"wpforms-1843-field_3-error\" required><label for=\"wpforms-1843-field_4\">Anfrage<\/label><input type=\"text\" id=\"wpforms-1843-field_4\" name=\"wpforms[fields][4]\" aria-errormessage=\"wpforms-1843-field_4-error\" ><!-- .wpforms-field-container --><input type=\"hidden\" name=\"wpforms[id]\" value=\"1843\">\t\t\t<input\n\t\t\t\ttype=\"hidden\"\n\t\t\t\tname=\"wpforms[nonce]\"\n\t\t\t\tvalue=\"0e8caf54f7\"\n\t\t\t\/><br \/>\n\t\t\t<input type=\"hidden\" name=\"wpforms[author]\" value=\"1\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-1843\" data-alt-text=\"Sending...\" data-submit-text=\"Send Inquiry\" aria-live=\"assertive\" value=\"wpforms-submit\">Anfrage senden<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kelingmed.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><input type=\"hidden\" name=\"trp-form-language\" value=\"de\"\/><\/form>\n<p>  <!-- .wpforms-container -->\t\t<\/p>\n<h3>Entdecken Sie mehr \u00fcber Keling Medical News<br \/>\n<\/h3>\n<h2>FAQ<\/h2>\n<p>\t\t\t\t\tAlles, was Sie \u00fcber die Produkte und Dienstleistungen von Keling Medical wissen m\u00fcssen<br \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<svg viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><br \/>\n\t\t\t\t\t\t\t\t<svg viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><br \/>\n\t\t\t\t\t\t\t\t\t\t\t\t<a tabindex=\"0\">Welche Arten von medizinischen Ger\u00e4ten stellt Keling Medical her?<\/a><\/p>\n<p>Keling Medical ist auf eine breite Palette von medizinischen Ger\u00e4ten spezialisiert, darunter Operationsleuchten, Operationstische, Krankenhausbetten, medizinische Wagen und andere hochwertige medizinische Ger\u00e4te. Unsere Produkte entsprechen den h\u00f6chsten Industriestandards und werden in Krankenh\u00e4usern, Kliniken und medizinischen Einrichtungen weltweit eingesetzt.<\/p>\n<p>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<svg viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><br \/>\n\t\t\t\t\t\t\t\t<svg viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><br \/>\n\t\t\t\t\t\t\t\t\t\t\t\t<a tabindex=\"0\">Sind die Produkte von Keling Medical f\u00fcr den internationalen Gebrauch zertifiziert?<\/a><\/p>\n<p>Ja, alle Produkte von Keling Medical sind zertifiziert und entsprechen den internationalen Normen. Wir haben verschiedene Zertifizierungen erhalten, darunter ISO 13485 und die CE-Kennzeichnung, die sicherstellen, dass unsere Produkte strenge Qualit\u00e4ts- und Sicherheitsstandards f\u00fcr den weltweiten Einsatz erf\u00fcllen.<\/p>\n<p>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<svg viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><br \/>\n\t\t\t\t\t\t\t\t<svg viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><br \/>\n\t\t\t\t\t\t\t\t\t\t\t\t<a tabindex=\"0\">Wie kann ich eine Bestellung bei Keling Medical aufgeben?<\/a><\/p>\n<p>Um eine Bestellung bei Keling Medical aufzugeben, kontaktieren Sie einfach unser Verkaufsteam per E-Mail oder Telefon oder verwenden Sie das Anfrageformular auf unserer Website. Wir werden mit Ihnen zusammenarbeiten, um Ihre spezifischen Bed\u00fcrfnisse zu verstehen, Produktdetails zu liefern und Sie durch den Bestellprozess zu f\u00fchren. Wir bieten auch flexible Versand- und Zahlungsoptionen an, um Ihre Anforderungen zu erf\u00fcllen.<\/p>\n<p>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<svg viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><br \/>\n\t\t\t\t\t\t\t\t<svg viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><br \/>\n\t\t\t\t\t\t\t\t\t\t\t\t<a tabindex=\"0\">Kann Keling Medical Produkte f\u00fcr spezifische Bed\u00fcrfnisse oder Anforderungen anpassen? <\/a><\/p>\n<p>Aber sicher! Wir bieten f\u00fcr viele unserer Produkte Anpassungsm\u00f6glichkeiten an, um die spezifischen Bed\u00fcrfnisse unserer Kunden besser zu erf\u00fcllen. Ganz gleich, ob es um die Anpassung von Merkmalen, Gr\u00f6\u00dfen oder Oberfl\u00e4chen geht, unser Team arbeitet eng mit den Kunden zusammen, um sicherzustellen, dass unsere Produkte ihren einzigartigen Spezifikationen entsprechen.<\/p>\n<p>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<svg viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><br \/>\n\t\t\t\t\t\t\t\t<svg viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><br \/>\n\t\t\t\t\t\t\t\t\t\t\t\t<a tabindex=\"0\">Bietet Keling Medical Kundendienst und Garantie?<\/a><\/p>\n<p>Ja, wir bieten umfassenden Kundendienst, einschlie\u00dflich Produktwartung, technische Unterst\u00fctzung und Fehlerbehebung. Auf alle unsere Produkte gew\u00e4hren wir eine Garantie, um sicherzustellen, dass Sie hochwertige und langlebige Ger\u00e4te erhalten. Unser Kundendienstteam steht Ihnen jederzeit zur Verf\u00fcgung, wenn Sie Fragen oder Probleme haben.<\/p>\n<p>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<svg viewbox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><br \/>\n\t\t\t\t\t\t\t\t<svg viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><br \/>\n\t\t\t\t\t\t\t\t\t\t\t\t<a tabindex=\"0\">Sind die Produkte von Keling Medical weltweit erh\u00e4ltlich?<\/a><\/p>\n<p>Ja, Keling Medical liefert seine Produkte in eine Vielzahl von L\u00e4ndern auf der ganzen Welt. Wir verf\u00fcgen \u00fcber ein starkes Vertriebsnetz und arbeiten mit Kunden aus verschiedenen Regionen zusammen, um eine rechtzeitige Lieferung und Unterst\u00fctzung f\u00fcr Krankenh\u00e4user und medizinische Einrichtungen auf der ganzen Welt zu gew\u00e4hrleisten. Nehmen Sie Kontakt mit uns auf, um die Versandoptionen f\u00fcr Ihren Standort zu besprechen.<\/p>\n<p>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:inquiry@shkeling.com\"><br \/>\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"51\" src=\"https:\/\/kelingmed.com\/wp-content\/uploads\/2024\/12\/keling-medical-logo.png\" alt=\"keling medizinisch-logo\" \/>\t\t\t\t\t\t\t\t<\/a><\/p>\n<h2>Erhalten Sie mehr Antworten \u00fcber Keling Medizinische Ger\u00e4te<\/h2>\n<p>Sollten Sie weitere Fragen zu medizinischen Ger\u00e4ten oder deren Verwendung haben, k\u00f6nnen Sie sich gerne an uns wenden. Wir bieten Ihnen detaillierte Informationen und Unterst\u00fctzung, die auf Ihre speziellen Bed\u00fcrfnisse zugeschnitten sind.<\/p>\n<p>\t\t\t\t\t<a href=\"mailto:inquiry@shkeling.com\"><br \/>\n\t\t\t\t\t\t\t\t\tJetzt anfragen<br \/>\n\t\t\t\t\t<\/a><\/p>\n<h2>Let&#8217;s Become Reliable Partners<\/h2>\n<form id=\"wpforms-form-874\" data-formid=\"874\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/wp-admin\/admin-ajax.php\" data-token=\"9ceda1c5c0f8ba4ff3db2b54017840b0\" data-trp-original-action=\"\/wp-admin\/admin-ajax.php\"><noscript>Please enable JavaScript in your browser to complete this form.<\/noscript>Please enable JavaScript in your browser to complete this form.<label for=\"wpforms-874-field_3\" aria-hidden=\"false\">Layout<\/label><label for=\"wpforms-874-field_2\">Name *<\/label><input type=\"text\" id=\"wpforms-874-field_2\" name=\"wpforms[fields][2]\" aria-errormessage=\"wpforms-874-field_2-error\" required><label for=\"wpforms-874-field_1\">Email *<\/label><input type=\"email\" id=\"wpforms-874-field_1\" name=\"wpforms[fields][1]\" spellcheck=\"false\" aria-errormessage=\"wpforms-874-field_1-error\" required><!-- .wpforms-field-container --><input type=\"hidden\" name=\"wpforms[id]\" value=\"874\">\t\t\t<input\n\t\t\t\ttype=\"hidden\"\n\t\t\t\tname=\"wpforms[nonce]\"\n\t\t\t\tvalue=\"02a80ba48a\"\n\t\t\t\/><br \/>\n\t\t\t<input type=\"hidden\" name=\"wpforms[author]\" value=\"1\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-874\" data-alt-text=\"Sending...\" data-submit-text=\"Send Inquiry\" aria-live=\"assertive\" value=\"wpforms-submit\">Anfrage senden<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kelingmed.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><input type=\"hidden\" name=\"trp-form-language\" value=\"de\"\/><\/form>\n<p>  <!-- .wpforms-container --><\/p>","protected":false},"excerpt":{"rendered":"<p>Keling Medical - Chinas Hersteller medizinischer Ger\u00e4te - nahm an der Arab Health 2024 teil, einer der gr\u00f6\u00dften und st\u00e4rksten medizinischen Fachmessen im Nahen Osten und international. Diese Veranstaltung war eine perfekte Gelegenheit, unsere fortschrittlichen L\u00f6sungen zu pr\u00e4sentieren und sich mit F\u00fchrungskr\u00e4ften, H\u00e4ndlern und medizinischen Fachleuten zu treffen.<\/p>","protected":false},"author":1,"featured_media":1890,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[31],"tags":[],"class_list":["post-1888","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-exhibition"],"amp_enabled":false,"_links":{"self":[{"href":"https:\/\/kelingmed.com\/de\/wp-json\/wp\/v2\/posts\/1888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kelingmed.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kelingmed.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kelingmed.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kelingmed.com\/de\/wp-json\/wp\/v2\/comments?post=1888"}],"version-history":[{"count":4,"href":"https:\/\/kelingmed.com\/de\/wp-json\/wp\/v2\/posts\/1888\/revisions"}],"predecessor-version":[{"id":1893,"href":"https:\/\/kelingmed.com\/de\/wp-json\/wp\/v2\/posts\/1888\/revisions\/1893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kelingmed.com\/de\/wp-json\/wp\/v2\/media\/1890"}],"wp:attachment":[{"href":"https:\/\/kelingmed.com\/de\/wp-json\/wp\/v2\/media?parent=1888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kelingmed.com\/de\/wp-json\/wp\/v2\/categories?post=1888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kelingmed.com\/de\/wp-json\/wp\/v2\/tags?post=1888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}